{"id":52012,"date":"2020-04-09T15:30:38","date_gmt":"2020-04-09T19:30:38","guid":{"rendered":"https:\/\/www.unhcr.ca\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/"},"modified":"2021-01-08T15:16:24","modified_gmt":"2021-01-08T20:16:24","slug":"yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens","status":"publish","type":"post","link":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/","title":{"rendered":"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb"},"content":{"rendered":"<p><img decoding=\"async\" class=\"wp-image-48276 size-full\" src=\"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg\" alt=\" width=\" height=\"653\" \/><\/p>\n<h2>Yusra Mardini, athl\u00e8te olympique et ambassadrice de bonne volont\u00e9 du HCR, parle de r\u00e9silience, de Tokyo 2020 et de la mani\u00e8re dont les Jeux olympiques rassemblent les gens<\/h2>\n<p><strong>Par Yusra Mardini, <em>tel que racont\u00e9 \u00e0 Hannah Scott<\/em><\/strong><\/p>\n<hr \/>\n<h3><em><strong>Yusra Mardini<\/strong>, une nageuse et r\u00e9fugi\u00e9e syrienne, a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s. En partageant son histoire touchante, Yusra d\u00e9fend la cause des r\u00e9fugi\u00e9s sur la sc\u00e8ne internationale et est devenue une porte-parole influente pour les personnes d\u00e9racin\u00e9es du monde entier.<\/em><\/h3>\n<hr \/>\n<p><strong>D\u00e8s votre plus jeune \u00e2ge, vous vouliez \u00eatre nageuse olympique. Qu\u2019est-ce que cela signifie pour vous d\u2019avoir fait partie de la toute premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s?<\/strong><\/p>\n<p>Quand la guerre a \u00e9clat\u00e9 en Syrie, j\u2019ai continu\u00e9 la natation en essayant de vivre normalement, mais la situation s\u2019est aggrav\u00e9e et il est devenu plus difficile d\u2019aller \u00e0 la piscine. J\u2019ai d\u00fb arr\u00eater les entra\u00eenements pendant deux ans; je pensais que mon r\u00eave allait prendre fin. Mais ma famille et moi avons surv\u00e9cu \u00e0 la guerre. Nous avons recommenc\u00e9 nos vies \u00e0 z\u00e9ro. Et avec mon \u00e9quipe, j\u2019ai r\u00e9alis\u00e9 mon r\u00eave olympique, ce qui signifiait tout pour moi.<\/p>\n<p><strong>En tant que r\u00e9fugi\u00e9e et athl\u00e8te olympique, vous occupez une place unique, une place que seules 10 personnes ont connu jusqu\u2019\u00e0 ce jour. Comment avez-vous v\u00e9cu cette exp\u00e9rience, un parcours que personne n\u2019a suivi jusqu\u2019\u00e0 maintenant?<\/strong><\/p>\n<p>En fait, c\u2019est gr\u00e2ce \u00e0 la natation que j\u2019ai pu m\u2019installer en Allemagne. Cela m\u2019a aid\u00e9e \u00e0 nouer des liens et \u00e0 retrouver une vie \u00ab normale \u00bb. La natation m\u2019a permis de vivre ma passion et m\u2019a donn\u00e9 un but. Bien s\u00fbr, les entra\u00eenements \u00e9taient difficiles : je nageais jusqu\u2019\u00e0 quatre heures par jour, tout en apprenant l\u2019allemand et en allant \u00e0 l\u2019\u00e9cole, mais tout cela en valait la peine.<\/p>\n<p><strong>Quand vous avez fui la Syrie, vous n\u2019aviez que 17 ans. Comme des milliers d\u2019autres r\u00e9fugi\u00e9s, vous avez d\u00fb faire la dangereuse travers\u00e9e en mer M\u00e9diterran\u00e9e. Pouvez-vous nous dire quelques mots sur cette exp\u00e9rience?<\/strong><\/p>\n<p>Ma soeur et moi avons failli p\u00e9rir pendant notre travers\u00e9e de la M\u00e9diterran\u00e9e. Comme la plupart des bateaux qui font ce p\u00e9riple, le n\u00f4tre \u00e9tait surcharg\u00e9, et le moteur s\u2019est arr\u00eat\u00e9 au beau milieu de la mer \u00c9g\u00e9e. Nous n\u2019avions que deux possibilit\u00e9s : paniquer et abandonner, ou agir. Ma soeur et moi avons saut\u00e9 dans l\u2019eau et nous avons pouss\u00e9 jusqu\u2019\u00e0 ce que nous ne puissions plus. Apr\u00e8s avoir nag\u00e9 pendant plus de trois heures et demie, nous sommes finalement arriv\u00e9es en Gr\u00e8ce.<\/p>\n<p>Nous ne sommes pas partis de chez nous pour trouver une vie plus facile ailleurs o\u00f9 on re\u00e7oit tout sur un plateau d\u2019argent. Nous avons fui \u00e0 cause des bombes, des balles et des pers\u00e9cutions. Et nous m\u00e9ritons d\u2019avoir les m\u00eames chances pour reconstruire notre vie et prendre notre avenir en main. Si vous voulez faire en sorte que ce monde soit plus \u00e9galitaire, je vous demande d\u2019offrir aux r\u00e9fugi\u00e9s la possibilit\u00e9 non seulement de survivre, mais aussi celle de s\u2019\u00e9panouir.<\/p>\n<p><strong>Pendant les Jeux olympiques de Rio 2016, votre histoire a \u00e9t\u00e9 une source d\u2019inspiration au Canada, et de nombreux Canadiens ont suivi votre parcours olympique. Il est certain qu\u2019ils vous suivront pendant les Jeux olympiques de Tokyo 2020. Qu\u2019est-ce que cela signifie pour vous d\u2019\u00eatre une source d\u2019inspiration non seulement pour les r\u00e9fugi\u00e9s, mais aussi pour tous les peuples du monde?<\/strong><\/p>\n<p>Je m\u2019entra\u00eene dur pour les Jeux olympiques de Tokyo 2020, mais j\u2019essaie aussi d\u2019am\u00e9liorer les choses pour les r\u00e9fugi\u00e9s. En tant qu\u2019ambassadrice de bonne volont\u00e9 du HCR, je dispose d\u2019une plateforme pour raconter mon histoire et celle des autres. Je veux inciter les r\u00e9fugi\u00e9s \u00e0 croire en eux-m\u00eames, et encourager la soci\u00e9t\u00e9 dans son ensemble \u00e0 croire en eux aussi. Apr\u00e8s tout, les r\u00e9fugi\u00e9s sont des personnes normales qui vivent des circonstances traumatisantes et bouleversantes, et sont capables de choses extraordinaires si on leur en donne la chance.<\/p>\n<blockquote>\n<p style=\"text-align: center;\"><strong>\u00ab Les r\u00e9fugi\u00e9s ne sont pas des fardeaux, mais des personnes qui peuvent apporter de grandes comp\u00e9tences et une grande \u00e9nergie \u00e0 la soci\u00e9t\u00e9. \u00bb<\/strong><\/p>\n<\/blockquote>\n<p><strong>Y a-t-il quelque chose que vous aimeriez dire aux Canadiens sur la situation des r\u00e9fugi\u00e9s, ou sur quelque chose qu\u2019ils ignorent \u00e0 leur sujet?<\/strong><\/p>\n<p>Les gens ne r\u00e9alisent pas que, pour un r\u00e9fugi\u00e9, le moment o\u00f9 vous vous arr\u00eatez de courir peut \u00eatre tout aussi difficile que celui o\u00f9 vous avez commenc\u00e9 de le faire. Ce n\u2019est qu\u2019au moment o\u00f9 j\u2019ai travers\u00e9 la derni\u00e8re fronti\u00e8re et que je me suis sentie en s\u00e9curit\u00e9 que j\u2019ai r\u00e9alis\u00e9 que j\u2019avais perdu bien plus que ma maison. J\u2019avais aussi perdu ma nationalit\u00e9 et mon identit\u00e9. De m\u00eame, ceux qui m\u2019entouraient n\u2019arrivaient plus \u00e0 trouver un sens \u00e0 leur vie ni leur estime personnelle. Ils \u00e9taient autrefois m\u00e9decins, ing\u00e9nieurs, enseignants et \u00e9tudiants. Et d\u00e9sormais ils n\u2019\u00e9taient plus que des r\u00e9fugi\u00e9s, r\u00e9duits \u00e0 une \u00e9tiquette. Les gens doivent d\u00e9passer cette \u00e9tiquette et imaginer l\u2019\u00e9tonnante contribution que les r\u00e9fugi\u00e9s peuvent apporter.<\/p>\n<p style=\"text-align: center;\"><a href='https:\/\/content.yudu.com\/web\/3ky23\/0A3ky24\/Printemps2020\/index.html' class='big-button bigblue' target=\"_blank\"><span style=\"color: #ffffff;\">LISEZ L&rsquo;\u00c9DITION EN LIGNE DU MAGAZINE DU HCR<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.<\/p>\n","protected":false},"author":36,"featured_media":52013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[48,45],"tags":[878,90,346,194,200,290,259,1033],"class_list":["post-52012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin","category-nouvelle","tag-ambassadrice-de-bonne-volonte","tag-hcr","tag-le-hcr","tag-refugiee","tag-refugies","tag-syriens","tag-unhcr-fr","tag-yusra-mardini-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Yusra Mardini : \u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb | Le HCR<\/title>\n<meta name=\"description\" content=\"Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb\" \/>\n<meta property=\"og:description\" content=\"Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/\" \/>\n<meta property=\"og:site_name\" content=\"HCR Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UNHCRCanada\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T19:30:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-08T20:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jack Nolos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNHCRCanada\" \/>\n<meta name=\"twitter:site\" content=\"@UNHCRCanada\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jack Nolos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/\"},\"author\":{\"name\":\"Jack Nolos\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/#\\\/schema\\\/person\\\/f4976eb360cbe05ea538bc4b08d3b29e\"},\"headline\":\"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb\",\"datePublished\":\"2020-04-09T19:30:38+00:00\",\"dateModified\":\"2021-01-08T20:16:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/\"},\"wordCount\":988,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unhcr.ca\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg\",\"keywords\":[\"ambassadrice de bonne volont\u00e9\",\"HCR\",\"le HCR\",\"r\u00e9fugi\u00e9e\",\"r\u00e9fugi\u00e9s\",\"Syriens\",\"unhcr\",\"Yusra Mardini\"],\"articleSection\":[\"Bulletin\",\"Nouvelle\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/\",\"url\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/\",\"name\":\"Yusra Mardini : \u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb | Le HCR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unhcr.ca\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg\",\"datePublished\":\"2020-04-09T19:30:38+00:00\",\"dateModified\":\"2021-01-08T20:16:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/#\\\/schema\\\/person\\\/f4976eb360cbe05ea538bc4b08d3b29e\"},\"description\":\"Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unhcr.ca\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unhcr.ca\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg\",\"width\":980,\"height\":653,\"caption\":\"Yusra Mardini, ambassadrice de bonne volont\u00e9 du HCR, rencontre des jeunes filles lors d\u2019une visite au camp de r\u00e9fugi\u00e9s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/#website\",\"url\":\"https:\\\/\\\/www.unhcr.ca\\\/\",\"name\":\"HCR Canada\",\"description\":\"L\u2019Agence des Nations Unies pour les r\u00e9fugi\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unhcr.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unhcr.ca\\\/#\\\/schema\\\/person\\\/f4976eb360cbe05ea538bc4b08d3b29e\",\"name\":\"Jack Nolos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f76742e96399100813d35b114145ee3d54a4002bf38e3207b1bd48aaa56e541e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f76742e96399100813d35b114145ee3d54a4002bf38e3207b1bd48aaa56e541e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f76742e96399100813d35b114145ee3d54a4002bf38e3207b1bd48aaa56e541e?s=96&d=mm&r=g\",\"caption\":\"Jack Nolos\"},\"url\":\"https:\\\/\\\/www.unhcr.ca\\\/fr\\\/news\\\/author\\\/jacknolos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yusra Mardini : \u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb | Le HCR","description":"Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb","og_description":"Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.","og_url":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/","og_site_name":"HCR Canada","article_publisher":"https:\/\/www.facebook.com\/UNHCRCanada","article_published_time":"2020-04-09T19:30:38+00:00","article_modified_time":"2021-01-08T20:16:24+00:00","og_image":[{"width":980,"height":653,"url":"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg","type":"image\/jpeg"}],"author":"Jack Nolos","twitter_card":"summary_large_image","twitter_creator":"@UNHCRCanada","twitter_site":"@UNHCRCanada","twitter_misc":{"\u00c9crit par":"Jack Nolos","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#article","isPartOf":{"@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/"},"author":{"name":"Jack Nolos","@id":"https:\/\/www.unhcr.ca\/#\/schema\/person\/f4976eb360cbe05ea538bc4b08d3b29e"},"headline":"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb","datePublished":"2020-04-09T19:30:38+00:00","dateModified":"2021-01-08T20:16:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/"},"wordCount":988,"commentCount":0,"image":{"@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg","keywords":["ambassadrice de bonne volont\u00e9","HCR","le HCR","r\u00e9fugi\u00e9e","r\u00e9fugi\u00e9s","Syriens","unhcr","Yusra Mardini"],"articleSection":["Bulletin","Nouvelle"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/","url":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/","name":"Yusra Mardini : \u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb | Le HCR","isPartOf":{"@id":"https:\/\/www.unhcr.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#primaryimage"},"image":{"@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg","datePublished":"2020-04-09T19:30:38+00:00","dateModified":"2021-01-08T20:16:24+00:00","author":{"@id":"https:\/\/www.unhcr.ca\/#\/schema\/person\/f4976eb360cbe05ea538bc4b08d3b29e"},"description":"Yusra Mardini a \u00e9t\u00e9 nomm\u00e9e la plus jeune ambassadrice de bonne volont\u00e9 du HCR en avril 2017 apr\u00e8s avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour participer aux Jeux olympiques de Rio 2016 au sein de la premi\u00e8re \u00e9quipe olympique de r\u00e9fugi\u00e9s.","breadcrumb":{"@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#primaryimage","url":"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg","contentUrl":"https:\/\/www.unhcr.ca\/wp-content\/uploads\/2020\/08\/RF2249236_201909161346_Jordan_JMC_0866-980x653-1.jpg","width":980,"height":653,"caption":"Yusra Mardini, ambassadrice de bonne volont\u00e9 du HCR, rencontre des jeunes filles lors d\u2019une visite au camp de r\u00e9fugi\u00e9s"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unhcr.ca\/fr\/news\/yusra-mardini-parle-resilience-tokyo-2020-maniere-dont-jeux-olympiques-rassemblent-gens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unhcr.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab Je veux inspirer les r\u00e9fugi\u00e9s \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.unhcr.ca\/#website","url":"https:\/\/www.unhcr.ca\/","name":"HCR Canada","description":"L\u2019Agence des Nations Unies pour les r\u00e9fugi\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unhcr.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.unhcr.ca\/#\/schema\/person\/f4976eb360cbe05ea538bc4b08d3b29e","name":"Jack Nolos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f76742e96399100813d35b114145ee3d54a4002bf38e3207b1bd48aaa56e541e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f76742e96399100813d35b114145ee3d54a4002bf38e3207b1bd48aaa56e541e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76742e96399100813d35b114145ee3d54a4002bf38e3207b1bd48aaa56e541e?s=96&d=mm&r=g","caption":"Jack Nolos"},"url":"https:\/\/www.unhcr.ca\/fr\/news\/author\/jacknolos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/posts\/52012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/comments?post=52012"}],"version-history":[{"count":0,"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/posts\/52012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/media\/52013"}],"wp:attachment":[{"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/media?parent=52012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/categories?post=52012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unhcr.ca\/fr\/wp-json\/wp\/v2\/tags?post=52012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}